{"id":971,"date":"2013-07-23T22:46:27","date_gmt":"2013-07-23T21:46:27","guid":{"rendered":"http:\/\/www.sopayaso.com\/blog\/?p=971"},"modified":"2013-07-23T22:46:27","modified_gmt":"2013-07-23T21:46:27","slug":"fiestas-santa-ana-2013-bercial","status":"publish","type":"post","link":"https:\/\/www.sopayaso.com\/blog\/2013\/07\/fiestas-santa-ana-2013-bercial\/","title":{"rendered":"Fiestas Santa Ana 2013 (Bercial)"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.sopayaso.com\/blog\/2013\/07\/fiestas-santa-ana-2013-bercial\/captura-de-pantalla-2013-07-21-a-las-23-27-41\/\" rel=\"attachment wp-att-973\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-973\" alt=\"Captura de pantalla 2013-07-21 a la(s) 23.27.41\" src=\"http:\/\/www.sopayaso.com\/blog\/wp-content\/uploads\/2013\/07\/Captura-de-pantalla-2013-07-21-a-las-23.27.41.png\" width=\"410\" height=\"576\" srcset=\"https:\/\/www.sopayaso.com\/blog\/wp-content\/uploads\/2013\/07\/Captura-de-pantalla-2013-07-21-a-las-23.27.41.png 513w, https:\/\/www.sopayaso.com\/blog\/wp-content\/uploads\/2013\/07\/Captura-de-pantalla-2013-07-21-a-las-23.27.41-213x300.png 213w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/a><\/p>\n<p>Un a\u00f1o m\u00e1s se acercan las fiestas de Santa Ana 2013, y como es habitual, a estas alturas ya esta casi todo preparado para recibir a nuestra patrona.<\/p>\n<p>Pe\u00f1as limpias, barras puestas y bebidas preparadas para pillarse unas melopeas de toma pan y moja. No nos olvidemos de la comida, imprescindible para cenar o almorzar en los d\u00edas de fiesta, ya que sin provisiones el alcohol se nos sube m\u00e1s r\u00e1pido de lo habitual y hay que cenar bien y despu\u00e9s almorzar para que se nos asiente el est\u00f3mago, que son muchos d\u00edas\u00a1\u00a1<\/p>\n<p>Sin m\u00e1s os dejo con el programa de Fiestas de este a\u00f1o, similar al de a\u00f1os anteriores. Est\u00e1is invitados a pasaros para celebrar con nosotros las fiestas y tomaros unos cubatas en nuestras pe\u00f1as.<\/p>\n<p>Felices Fiestas\u00a1\u00a1<\/p>\n<h2>Mi\u00e9rcoles 24 : V\u00edsperas<\/h2>\n<p>20:00 Repique de campanas.<\/p>\n<p>20:30 \u00a1\u00a1\u00a1\u00a1BERCIAL DESPIERTA QUE ESTAMOS EN FIESTAS!!!!<\/p>\n<p>23:30 Todo el mundo a buscar la charanga.<\/p>\n<p>23:45 Preg\u00f3n de fiestas y chupinazo.<\/p>\n<p>23:59 Inauguraci\u00f3n de pe\u00f1as amenizado por la charanga \u201cChicuelina\u201d.<\/p>\n<h2>Jueves 25: Santiago<\/h2>\n<p>12:30 \u00a1\u00a1\u00a1\u00a1ARRIIIIIIBA BERCIAL AAAARRIBA!!!!<\/p>\n<p>13:30 Misa en honor de Santiago Ap\u00f3stol.<\/p>\n<p>14:30 \u00a1\u00a1Tradicional vermouth!!<\/p>\n<p>19:00 Bajada de Santa Ana desde su ermita hasta la iglesia acompa\u00f1ada de jotas populares.<\/p>\n<p>21:00 Jotas con el grupo \u201cLa ronda segoviana\u201d.<\/p>\n<p>00:00 Discom\u00f3vil\u00a0 \u201cStar Night\u201d y baile de disfraces.<\/p>\n<h2><strong>Viernes 26: Santa Ana La Grande<\/strong><\/h2>\n<p>08:00 \u00a1\u00a1\u00bf NO TE DA VERG\u00dcENZA LLEGAR A ESTAS HORAS ?!!<\/p>\n<p>13:00Misa en honor a Santa Ana. A continuaci\u00f3n procesi\u00f3n acompa\u00f1ada de jotas populares.<\/p>\n<p>14:30 \u00a1\u00a1\u00a1\u00a1\u00a1Tos pal tele que nos espera el vermouth!!!!!<\/p>\n<p>18:00 A POR LOS TOROS\u00a0 \u00a1OOOOOOEEEEE!<\/p>\n<p>18:30 Encuentro con la charanga.<\/p>\n<p>19:00 Tradicional encierro por el casco antiguo.<\/p>\n<p>00:00 Verbena amenizada por la orquesta \u201cLos Tony\u00b4s\u201d.<\/p>\n<p>02:00 \u00a1\u00a1\u00a1\u00a1Bingoooooo!!!! Cantado por las mozas del pueblo.<\/p>\n<p>03:00 Tradicional meada en los campos del municipio que est\u00e1n mu secos.<\/p>\n<p>04:30 Discom\u00f3vil \u201c Studio 54 \u201dpara acabar la noche.<\/p>\n<h2>S\u00e1bado 27 :Santa Ana la chica<\/h2>\n<p>09:00 \u00a1\u00a1VAMOS PA\u2019RRIBA , QUE EL QUE VALE PA TRANSNOCHAR VALE PA MADRUGAR!!<\/p>\n<p>11:00 Santa Misa de difuntos.<\/p>\n<p>12:00 Diversi\u00f3n para todos y ba\u00f1o de espuma.<\/p>\n<p>14:00 \u00a1\u00a1Santo vermouth!!<\/p>\n<p>15:00 Gran comida popular\u00a0 \u201cPaella\u201d (solo socios).<\/p>\n<p>19:30 Subida de Santa Ana acompa\u00f1ada con jotas tradicionales.<\/p>\n<p>00:00 Verbena amenizada por la orquesta\u00a0 \u201cEscalada 921\u201d.<\/p>\n<p>02:00 Bingo cantado por los mozos del pueblo.<\/p>\n<p>04:00 Discom\u00f3vil \u201cYomi \u201d patrocinada por el teleclub.<\/p>\n<p>06:00 \u00a1\u00a1A regar los huertos!!<\/p>\n<h2><strong>Domingo 28 :San Queremos<\/strong><\/h2>\n<p>08.00 \u00a1\u00a1\u00a1\u00a1A CORTAR LAS CALLES MATARILE RILE RILE!!!!<\/p>\n<p>09:00 Gran Encierro campestre.<\/p>\n<p>09:05\u00a1SABEMOS CUANDO EMPIZA PERO NO CUANDO ACABA!<\/p>\n<p>11:30 \u00a1\u00a1\u00a1A COMER HUEV\u00cdNES!!!<\/p>\n<p>13:00 Misa de domingo.<\/p>\n<p>15:30 A dormir la mona.<\/p>\n<p>19:00 Gran gymkhana y a continuaci\u00f3n encierros infantiles para ver a las j\u00f3venes promesas con el grupo \u201cTira t\u00fa que yo estoy cansao\u201d.<\/p>\n<p>21:30 A acabar lo que queda de bebida (si es que queda algo).<\/p>\n<p>00:00 A descansar y hasta el a\u00f1o que viene \u00a1APARCAO!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o m\u00e1s se acercan las fiestas de Santa Ana 2013, y como es habitual, a estas alturas ya esta casi todo preparado para recibir a nuestra patrona. Pe\u00f1as limpias, barras puestas y bebidas preparadas para pillarse unas melopeas de toma pan y moja. No nos olvidemos de la comida, imprescindible para cenar o almorzar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[282,99,169,257,200],"class_list":["post-971","post","type-post","status-publish","format-standard","hentry","category-general","tag-282","tag-bercial","tag-fiestas","tag-santana","tag-segovia"],"_links":{"self":[{"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/posts\/971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/comments?post=971"}],"version-history":[{"count":0,"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/posts\/971\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/media?parent=971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/categories?post=971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sopayaso.com\/blog\/wp-json\/wp\/v2\/tags?post=971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}